{"id":976,"date":"2024-01-21T17:15:14","date_gmt":"2024-01-21T16:15:14","guid":{"rendered":"https:\/\/holidaysicily.net\/?page_id=976"},"modified":"2026-04-08T10:49:50","modified_gmt":"2026-04-08T08:49:50","slug":"ulivo","status":"publish","type":"page","link":"https:\/\/holidaysicily.net\/en\/ulivo\/","title":{"rendered":"Ulivo"},"content":{"rendered":"<p class=\"attachment\"><a href='https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-38-e1743597292974.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-38-e1743597292974.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"976\" class=\"elementor elementor-976\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e75a226 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e75a226\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:3189,&quot;url&quot;:&quot;https:\\\/\\\/holidaysicily.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/scopello-1.jpeg&quot;},{&quot;id&quot;:3194,&quot;url&quot;:&quot;https:\\\/\\\/holidaysicily.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/san-vito-lo-capo.jpeg&quot;},{&quot;id&quot;:3193,&quot;url&quot;:&quot;https:\\\/\\\/holidaysicily.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Riserva-1.jpeg&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-257801c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"257801c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-29f7c1d e-con-full elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-laptop e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"29f7c1d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b2b7917 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b2b7917\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d775b29 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d775b29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-823393c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"823393c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a38d61e elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a38d61e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t+39 333 9360695\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a35535 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8a35535\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-608d069 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"608d069\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t+39 366 2522334\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40bf715 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"40bf715\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc4f4b3 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bc4f4b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVia delle Ostriche 47, Alcamo, Italy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb5ade8 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"bb5ade8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1eabf6 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b1eabf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tholidaysicily65@gmail.com\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e00650 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8e00650\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-89370d6 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"89370d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b28b47 elementor-shape-circle e-grid-align-right elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"3b28b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-ba17d6f\" href=\"https:\/\/www.facebook.com\/HolidaySicilyCasaVacanze\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-0be1f96\" href=\"https:\/\/www.instagram.com\/holiday_sicily\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d56fa4c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d56fa4c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbf2604 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cbf2604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c1f3aa e-con-full elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4c1f3aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8f3e4a1 e-con-full elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-laptop e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8f3e4a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3e29fbf e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"3e29fbf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3beb40 wpr-main-menu-align-left wpr-main-menu-align--laptopleft wpr-main-menu-align--tabletleft wpr-main-menu-align--mobileleft wpr-pointer-underline wpr-pointer-line-fx wpr-pointer-fx-fade wpr-sub-icon-caret-down wpr-sub-menu-fx-fade wpr-nav-menu-bp-mobile wpr-mobile-menu-full-width wpr-mobile-menu-item-align-center wpr-mobile-toggle-v1 wpr-sub-divider-yes wpr-mobile-divider-yes elementor-widget elementor-widget-wpr-nav-menu\" data-id=\"b3beb40\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;menu_layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"wpr-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"wpr-nav-menu-container wpr-nav-menu-horizontal\" data-trigger=\"hover\" data-consider-header=\"\" data-scroll-speed=\"500\"><ul id=\"menu-1-b3beb40\" class=\"wpr-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-106\"><a href=\"https:\/\/holidaysicily.net\/en\/\" class=\"wpr-menu-item wpr-pointer-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-109\"><a href=\"https:\/\/holidaysicily.net\/en\/villa\/\" class=\"wpr-menu-item wpr-pointer-item\">Villa<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1413\"><a href=\"https:\/\/holidaysicily.net\/en\/appartamenti\/\" class=\"wpr-menu-item wpr-pointer-item\">Appartamenti<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1944\"><a href=\"https:\/\/holidaysicily.net\/en\/noleggio-auto\/\" class=\"wpr-menu-item wpr-pointer-item\">Noleggio auto<\/a><\/li>\n<\/ul><\/nav><nav class=\"wpr-mobile-nav-menu-container\"><div class=\"wpr-mobile-toggle-wrap\"><div class=\"wpr-mobile-toggle\"><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><\/div><\/div><ul id=\"mobile-menu-2-b3beb40\" class=\"wpr-mobile-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-106\"><a href=\"https:\/\/holidaysicily.net\/en\/\" class=\"wpr-mobile-menu-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-109\"><a href=\"https:\/\/holidaysicily.net\/en\/villa\/\" class=\"wpr-mobile-menu-item\">Villa<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1413\"><a href=\"https:\/\/holidaysicily.net\/en\/appartamenti\/\" class=\"wpr-mobile-menu-item\">Appartamenti<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1944\"><a href=\"https:\/\/holidaysicily.net\/en\/noleggio-auto\/\" class=\"wpr-mobile-menu-item\">Noleggio auto<\/a><\/li>\n<\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f68ae0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8f68ae0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cdaa79e elementor-widget__width-initial e-transform elementor-widget elementor-widget-image\" data-id=\"cdaa79e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.98,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/holidaysicily.net\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"227\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png\" class=\"attachment-large size-large wp-image-287\" alt=\"\" srcset=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png 1024w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-300x85.png 300w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-768x218.png 768w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1536x436.png 1536w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f054e7 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"7f054e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afab763 wpr-main-menu-align-left wpr-main-menu-align--laptopleft wpr-main-menu-align--tabletleft wpr-main-menu-align--mobileleft wpr-pointer-underline wpr-pointer-line-fx wpr-pointer-fx-fade wpr-sub-icon-caret-down wpr-sub-menu-fx-fade wpr-nav-menu-bp-mobile wpr-mobile-menu-full-width wpr-mobile-menu-item-align-center wpr-mobile-toggle-v1 wpr-sub-divider-yes wpr-mobile-divider-yes elementor-widget elementor-widget-wpr-nav-menu\" data-id=\"afab763\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;menu_layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"wpr-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"wpr-nav-menu-container wpr-nav-menu-horizontal\" data-trigger=\"hover\" data-consider-header=\"\" data-scroll-speed=\"500\"><ul id=\"menu-1-afab763\" class=\"wpr-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-105\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/holidaysicily.net\/en\/servizi\/\" class=\"wpr-menu-item wpr-pointer-item\">Servizi<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1456\"><a href=\"https:\/\/holidaysicily.net\/en\/noleggio-auto\/\" class=\"wpr-sub-menu-item\">Noleggio auto<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1457\"><a href=\"https:\/\/holidaysicily.net\/en\/escursioni-in-barca\/\" class=\"wpr-sub-menu-item\">Escursioni in barca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1458\"><a href=\"https:\/\/holidaysicily.net\/en\/segesta-tour-4x4\/\" class=\"wpr-sub-menu-item\">Segesta Tour 4\u00d74<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-1945\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"#\" class=\"wpr-menu-item wpr-pointer-item\">Altro<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-103\"><a href=\"https:\/\/holidaysicily.net\/en\/nei-dintorni\/\" class=\"wpr-sub-menu-item\">Nei Dintorni<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-104\"><a href=\"https:\/\/holidaysicily.net\/en\/condizioni\/\" class=\"wpr-sub-menu-item\">Condizioni<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1946\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/holidaysicily.net\/en\/contattaci\/\" class=\"wpr-menu-item wpr-pointer-item\">Contatti<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2404\"><a href=\"https:\/\/holidaysicily.net\/en\/dove-siamo\/\" class=\"wpr-sub-menu-item\">Dove siamo<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav><nav class=\"wpr-mobile-nav-menu-container\"><div class=\"wpr-mobile-toggle-wrap\"><div class=\"wpr-mobile-toggle\"><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><\/div><\/div><ul id=\"mobile-menu-2-afab763\" class=\"wpr-mobile-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-105\"><a href=\"https:\/\/holidaysicily.net\/en\/servizi\/\" class=\"wpr-mobile-menu-item\">Servizi<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1456\"><a href=\"https:\/\/holidaysicily.net\/en\/noleggio-auto\/\" class=\"wpr-mobile-sub-menu-item\">Noleggio auto<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1457\"><a href=\"https:\/\/holidaysicily.net\/en\/escursioni-in-barca\/\" class=\"wpr-mobile-sub-menu-item\">Escursioni in barca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1458\"><a href=\"https:\/\/holidaysicily.net\/en\/segesta-tour-4x4\/\" class=\"wpr-mobile-sub-menu-item\">Segesta Tour 4\u00d74<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-1945\"><a href=\"#\" class=\"wpr-mobile-menu-item\">Altro<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-103\"><a href=\"https:\/\/holidaysicily.net\/en\/nei-dintorni\/\" class=\"wpr-mobile-sub-menu-item\">Nei Dintorni<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-104\"><a href=\"https:\/\/holidaysicily.net\/en\/condizioni\/\" class=\"wpr-mobile-sub-menu-item\">Condizioni<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1946\"><a href=\"https:\/\/holidaysicily.net\/en\/contattaci\/\" class=\"wpr-mobile-menu-item\">Contatti<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2404\"><a href=\"https:\/\/holidaysicily.net\/en\/dove-siamo\/\" class=\"wpr-mobile-sub-menu-item\">Dove siamo<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17d4118 e-con-full elementor-hidden-desktop e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"17d4118\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1908034 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1908034\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd7a45a wpr-nav-menu-bp-tablet wpr-mobile-toggle-v4 wpr-main-menu-align-left wpr-main-menu-align--laptopleft wpr-main-menu-align--tabletleft wpr-main-menu-align--mobileleft wpr-pointer-underline wpr-pointer-line-fx wpr-pointer-fx-fade wpr-sub-icon-caret-down wpr-sub-menu-fx-fade wpr-mobile-menu-full-width wpr-sub-divider-yes wpr-mobile-divider-yes elementor-widget elementor-widget-wpr-nav-menu\" data-id=\"dd7a45a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;menu_layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"wpr-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"wpr-nav-menu-container wpr-nav-menu-horizontal\" data-trigger=\"hover\" data-consider-header=\"\" data-scroll-speed=\"500\"><ul id=\"menu-1-dd7a45a\" class=\"wpr-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-87\"><a href=\"https:\/\/holidaysicily.net\/en\/\" class=\"wpr-menu-item wpr-pointer-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-97\"><a href=\"https:\/\/holidaysicily.net\/en\/villa\/\" class=\"wpr-menu-item wpr-pointer-item\">Villa<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-98\"><a href=\"https:\/\/holidaysicily.net\/en\/appartamenti\/\" class=\"wpr-menu-item wpr-pointer-item\">Appartamenti<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1462\"><a href=\"https:\/\/holidaysicily.net\/en\/noleggio-auto\/\" class=\"wpr-menu-item wpr-pointer-item\">Noleggio auto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-96\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/holidaysicily.net\/en\/contattaci\/\" class=\"wpr-menu-item wpr-pointer-item\">Contatti<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2403\"><a href=\"https:\/\/holidaysicily.net\/en\/dove-siamo\/\" class=\"wpr-sub-menu-item\">Dove siamo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-101\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/holidaysicily.net\/en\/servizi\/\" class=\"wpr-menu-item wpr-pointer-item\">Servizi<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1463\"><a href=\"https:\/\/holidaysicily.net\/en\/escursioni-in-barca\/\" class=\"wpr-sub-menu-item\">Escursioni in barca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1464\"><a href=\"https:\/\/holidaysicily.net\/en\/segesta-tour-4x4\/\" class=\"wpr-sub-menu-item\">Segesta Tour 4\u00d74<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-1948\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"#\" class=\"wpr-menu-item wpr-pointer-item\">Altro<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-100\"><a href=\"https:\/\/holidaysicily.net\/en\/condizioni\/\" class=\"wpr-sub-menu-item\">Condizioni<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-99\"><a href=\"https:\/\/holidaysicily.net\/en\/nei-dintorni\/\" class=\"wpr-sub-menu-item\">Nei Dintorni<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav><nav class=\"wpr-mobile-nav-menu-container\"><div class=\"wpr-mobile-toggle-wrap\"><div class=\"wpr-mobile-toggle\"><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><\/div><\/div><ul id=\"mobile-menu-2-dd7a45a\" class=\"wpr-mobile-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-87\"><a href=\"https:\/\/holidaysicily.net\/en\/\" class=\"wpr-mobile-menu-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-97\"><a href=\"https:\/\/holidaysicily.net\/en\/villa\/\" class=\"wpr-mobile-menu-item\">Villa<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-98\"><a href=\"https:\/\/holidaysicily.net\/en\/appartamenti\/\" class=\"wpr-mobile-menu-item\">Appartamenti<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1462\"><a href=\"https:\/\/holidaysicily.net\/en\/noleggio-auto\/\" class=\"wpr-mobile-menu-item\">Noleggio auto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-96\"><a href=\"https:\/\/holidaysicily.net\/en\/contattaci\/\" class=\"wpr-mobile-menu-item\">Contatti<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2403\"><a href=\"https:\/\/holidaysicily.net\/en\/dove-siamo\/\" class=\"wpr-mobile-sub-menu-item\">Dove siamo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-101\"><a href=\"https:\/\/holidaysicily.net\/en\/servizi\/\" class=\"wpr-mobile-menu-item\">Servizi<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1463\"><a href=\"https:\/\/holidaysicily.net\/en\/escursioni-in-barca\/\" class=\"wpr-mobile-sub-menu-item\">Escursioni in barca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1464\"><a href=\"https:\/\/holidaysicily.net\/en\/segesta-tour-4x4\/\" class=\"wpr-mobile-sub-menu-item\">Segesta Tour 4\u00d74<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-1948\"><a href=\"#\" class=\"wpr-mobile-menu-item\">Altro<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-100\"><a href=\"https:\/\/holidaysicily.net\/en\/condizioni\/\" class=\"wpr-mobile-sub-menu-item\">Condizioni<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-99\"><a href=\"https:\/\/holidaysicily.net\/en\/nei-dintorni\/\" class=\"wpr-mobile-sub-menu-item\">Nei Dintorni<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1853e6 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"f1853e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2d7e31 e-transform elementor-widget elementor-widget-image\" data-id=\"a2d7e31\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.98,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.98,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.98,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/holidaysicily.net\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"227\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png\" class=\"attachment-large size-large wp-image-287\" alt=\"\" srcset=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png 1024w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-300x85.png 300w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-768x218.png 768w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1536x436.png 1536w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de28e11 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"de28e11\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23fda8b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"23fda8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appartamento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89de92e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"89de92e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ulivo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1512b98 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1512b98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a37a3c3 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a37a3c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appartamento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbb82da elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bbb82da\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scopri l'appartamento Ulivo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48d542a elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"48d542a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Appartamento accogliente con vista panoramica sul mare, l\u2019appartamento Ulivo si distingue per interni raffinati, ampio balcone e tonalit\u00e0 naturali che creano un\u2019atmosfera serena e rilassante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e5baea e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7e5baea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c0791bb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"c0791bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3684471 elementor-hidden-desktop elementor-hidden-laptop elementor-widget elementor-widget-spacer\" data-id=\"3684471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bdf3e89 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"bdf3e89\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4733b19 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4733b19\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-576a595 elementor-widget elementor-widget-heading\" data-id=\"576a595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descrizione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1e473c elementor-widget elementor-widget-text-editor\" data-id=\"f1e473c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La casa \u00e8 ubicata in un tranquillo quartiere, su una stradina di 200 metri dal mare, in localit\u00e0 Alcamo Marina, distante 4 km circa dal capoluogo comunale di Alcamo, Balestrate e Castellammare del Golfo. E&#8217; situata al centro del Golfo di Castellammare, caratterizzata da una grande spiaggia di sabbia dorata (lunga circa 7 km), considerata tra le pi\u00f9 belle d&#8217;Italia, sia per estensione che per la qualit\u00e0 della sabbia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4901ef7 e-grid e-con-full wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4901ef7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c611ba4 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c611ba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t2\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMatrimoniali\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad5b324 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ad5b324\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t1\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDivano Letto\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5009c elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3a5009c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-shower\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M304,320a16,16,0,1,0,16,16A16,16,0,0,0,304,320Zm32-96a16,16,0,1,0,16,16A16,16,0,0,0,336,224Zm32,64a16,16,0,1,0-16-16A16,16,0,0,0,368,288Zm-32,32a16,16,0,1,0-16-16A16,16,0,0,0,336,320Zm-32-64a16,16,0,1,0,16,16A16,16,0,0,0,304,256Zm128-32a16,16,0,1,0-16-16A16,16,0,0,0,432,224Zm-48,16a16,16,0,1,0,16-16A16,16,0,0,0,384,240Zm-16-48a16,16,0,1,0,16,16A16,16,0,0,0,368,192Zm96,32a16,16,0,1,0,16,16A16,16,0,0,0,464,224Zm32-32a16,16,0,1,0,16,16A16,16,0,0,0,496,192Zm-64,64a16,16,0,1,0,16,16A16,16,0,0,0,432,256Zm-32,32a16,16,0,1,0,16,16A16,16,0,0,0,400,288Zm-64,64a16,16,0,1,0,16,16A16,16,0,0,0,336,352Zm-32,32a16,16,0,1,0,16,16A16,16,0,0,0,304,384Zm64-64a16,16,0,1,0,16,16A16,16,0,0,0,368,320Zm21.65-218.35-11.3-11.31a16,16,0,0,0-22.63,0L350.05,96A111.19,111.19,0,0,0,272,64c-19.24,0-37.08,5.3-52.9,13.85l-10-10A121.72,121.72,0,0,0,123.44,32C55.49,31.5,0,92.91,0,160.85V464a16,16,0,0,0,16,16H48a16,16,0,0,0,16-16V158.4c0-30.15,21-58.2,51-61.93a58.38,58.38,0,0,1,48.93,16.67l10,10C165.3,138.92,160,156.76,160,176a111.23,111.23,0,0,0,32,78.05l-5.66,5.67a16,16,0,0,0,0,22.62l11.3,11.31a16,16,0,0,0,22.63,0L389.65,124.28A16,16,0,0,0,389.65,101.65Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t1\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBagni\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b57d9d9 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b57d9d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-friends\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 256c61.9 0 112-50.1 112-112S253.9 32 192 32 80 82.1 80 144s50.1 112 112 112zm76.8 32h-8.3c-20.8 10-43.9 16-68.5 16s-47.6-6-68.5-16h-8.3C51.6 288 0 339.6 0 403.2V432c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48v-28.8c0-63.6-51.6-115.2-115.2-115.2zM480 256c53 0 96-43 96-96s-43-96-96-96-96 43-96 96 43 96 96 96zm48 32h-3.8c-13.9 4.8-28.6 8-44.2 8s-30.3-3.2-44.2-8H432c-20.4 0-39.2 5.9-55.7 15.4 24.4 26.3 39.7 61.2 39.7 99.8v38.4c0 2.2-.5 4.3-.6 6.4H592c26.5 0 48-21.5 48-48 0-61.9-50.1-112-112-112z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t6\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPersone\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f3a5021 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"f3a5021\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e9de5f3 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"e9de5f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4c5c4ca e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4c5c4ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56f38fe elementor-widget elementor-widget-heading\" data-id=\"56f38fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Interno<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed4dafe elementor-widget elementor-widget-text-editor\" data-id=\"ed4dafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>2 camere da letto matrimoniali<\/li><li>1 divano letto una piazza 1\/2 nel soggiorno\/cucina<\/li><li>1 bagno completo di box doccia<\/li><li>TV Satellitare, frigo, congelatore, lavatrice, condizionatore, cucina completa di forno a microonde e utensili vari<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bee9dc0 elementor-widget elementor-widget-heading\" data-id=\"bee9dc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Esterno<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-808427a elementor-widget elementor-widget-text-editor\" data-id=\"808427a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Grande balcone con veranda vista mare, con arredamento da giardino<\/li><li>1 posto auto, parcheggio interno alla struttura<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7226d29 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"7226d29\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f8f417 elementor-hidden-desktop elementor-hidden-laptop elementor-widget elementor-widget-spacer\" data-id=\"4f8f417\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0ec9c7a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"0ec9c7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c8fe78 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5c8fe78\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servizi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dad3b71 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dad3b71\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servizi inclusi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e06403 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"9e06403\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b0702be e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b0702be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b038e73 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b038e73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWI-FI\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tServizio wifi gratuito\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1172422 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1172422\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2383c70 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2383c70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hot-tub\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M414.21 177.65c1.02 8.21 7.75 14.35 15.75 14.35h16.12c9.51 0 17.08-8.57 16-18.35-4.34-39.11-22.4-74.53-50.13-97.16-17.37-14.17-28.82-36.75-31.98-62.15C378.96 6.14 372.22 0 364.23 0h-16.12c-9.51 0-17.09 8.57-16 18.35 4.34 39.11 22.4 74.53 50.13 97.16 17.36 14.17 28.82 36.75 31.97 62.14zm-108 0c1.02 8.21 7.75 14.35 15.75 14.35h16.12c9.51 0 17.08-8.57 16-18.35-4.34-39.11-22.4-74.53-50.13-97.16-17.37-14.17-28.82-36.75-31.98-62.15C270.96 6.14 264.22 0 256.23 0h-16.12c-9.51 0-17.09 8.57-16 18.35 4.34 39.11 22.4 74.53 50.13 97.16 17.36 14.17 28.82 36.75 31.97 62.14zM480 256H256l-110.93-83.2a63.99 63.99 0 0 0-38.4-12.8H64c-35.35 0-64 28.65-64 64v224c0 35.35 28.65 64 64 64h384c35.35 0 64-28.65 64-64V288c0-17.67-14.33-32-32-32zM128 440c0 4.42-3.58 8-8 8h-16c-4.42 0-8-3.58-8-8V328c0-4.42 3.58-8 8-8h16c4.42 0 8 3.58 8 8v112zm96 0c0 4.42-3.58 8-8 8h-16c-4.42 0-8-3.58-8-8V328c0-4.42 3.58-8 8-8h16c4.42 0 8 3.58 8 8v112zm96 0c0 4.42-3.58 8-8 8h-16c-4.42 0-8-3.58-8-8V328c0-4.42 3.58-8 8-8h16c4.42 0 8 3.58 8 8v112zm96 0c0 4.42-3.58 8-8 8h-16c-4.42 0-8-3.58-8-8V328c0-4.42 3.58-8 8-8h16c4.42 0 8 3.58 8 8v112zM64 128c35.35 0 64-28.65 64-64S99.35 0 64 0 0 28.65 0 64s28.65 64 64 64z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLenzuola e asciugamani\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInclusi nel prezzo\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2b3cd0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b2b3cd0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc10b49 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"dc10b49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-power-off\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 54.1c63 45 104 118.6 104 201.9 0 136.8-110.8 247.7-247.5 248C120 504.3 8.2 393 8 256.4 7.9 173.1 48.9 99.3 111.8 54.2c11.7-8.3 28-4.8 35 7.7L162.6 90c5.9 10.5 3.1 23.8-6.6 31-41.5 30.8-68 79.6-68 134.9-.1 92.3 74.5 168.1 168 168.1 91.6 0 168.6-74.2 168-169.1-.3-51.8-24.7-101.8-68.1-134-9.7-7.2-12.4-20.5-6.5-30.9l15.8-28.1c7-12.4 23.2-16.1 34.8-7.8zM296 264V24c0-13.3-10.7-24-24-24h-32c-13.3 0-24 10.7-24 24v240c0 13.3 10.7 24 24 24h32c13.3 0 24-10.7 24-24z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEnergia elettrica, gas e acqua\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTutto incluso\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6bbc000 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"6bbc000\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb4600b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"eb4600b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-parking\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tParcheggio\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t1  posto auto\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80a2e6a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"80a2e6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servizi non inclusi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03e0163 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"03e0163\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>*La piscina \u00e8 ad uso <strong>esclusivo\u00a0<\/strong>della Villa Oleandro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a33e0a elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5a33e0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cambio lenzuola, cambio asciugamani e possibilit\u00e0 di pulizia extra dell&#8217;appartamento. <strong>Contattare<\/strong> la struttura per <strong>aggiungere<\/strong> i servizi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0010342 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"0010342\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc3555d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fc3555d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Foto dell'appartamento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-058783f elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"058783f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scopri l'interno e l'esterno dell'appartamento Ulivo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bebe5c elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"1bebe5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#foto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bd8f75 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1bd8f75\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f05ae08 elementor-widget elementor-widget-menu-anchor\" data-id=\"f05ae08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"foto\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41d4f00 wpr-grid-columns--laptop3 wpr-grid-columns-4 wpr-grid-columns--tablet3 wpr-grid-columns--mobile1 wpr-grid-pagination-center elementor-widget elementor-widget-wpr-media-grid\" data-id=\"41d4f00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-media-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"wpr-grid wpr-media-grid elementor-clearfix\" data-settings=\"{&quot;layout&quot;:&quot;masonry&quot;,&quot;columns_desktop&quot;:4,&quot;gutter_hr&quot;:20,&quot;gutter_hr_mobile&quot;:20,&quot;gutter_hr_mobile_extra&quot;:20,&quot;gutter_hr_tablet&quot;:20,&quot;gutter_hr_tablet_extra&quot;:20,&quot;gutter_hr_laptop&quot;:20,&quot;gutter_hr_widescreen&quot;:20,&quot;gutter_vr&quot;:20,&quot;gutter_vr_mobile&quot;:20,&quot;gutter_vr_mobile_extra&quot;:20,&quot;gutter_vr_tablet&quot;:20,&quot;gutter_vr_tablet_extra&quot;:20,&quot;gutter_vr_laptop&quot;:20,&quot;gutter_vr_widescreen&quot;:20,&quot;animation&quot;:&quot;zoom&quot;,&quot;animation_duration&quot;:0.3,&quot;animation_delay&quot;:0.1,&quot;deeplinking&quot;:&quot;&quot;,&quot;filters_default_filter&quot;:&quot;&quot;,&quot;filters_linkable&quot;:&quot;no&quot;,&quot;filters_count&quot;:&quot;&quot;,&quot;filters_hide_empty&quot;:&quot;no&quot;,&quot;filters_animation&quot;:&quot;default&quot;,&quot;filters_animation_duration&quot;:0.3,&quot;filters_animation_delay&quot;:0.1,&quot;pagination_type&quot;:&quot;load-more&quot;,&quot;pagination_max_pages&quot;:1,&quot;lightbox&quot;:{&quot;selector&quot;:&quot;.wpr-grid-image-wrap&quot;,&quot;iframeMaxWidth&quot;:&quot;60%&quot;,&quot;hash&quot;:false,&quot;autoplay&quot;:&quot;&quot;,&quot;pause&quot;:5000,&quot;progressBar&quot;:&quot;&quot;,&quot;counter&quot;:&quot;true&quot;,&quot;controls&quot;:&quot;true&quot;,&quot;getCaptionFromTitleOrAlt&quot;:&quot;&quot;,&quot;thumbnail&quot;:&quot;&quot;,&quot;showThumbByDefault&quot;:&quot;&quot;,&quot;share&quot;:&quot;&quot;,&quot;zoom&quot;:&quot;true&quot;,&quot;fullScreen&quot;:&quot;true&quot;,&quot;download&quot;:&quot;&quot;}}\"><article class=\"wpr-grid-item elementor-clearfix post-2790 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/DRONE-1-e1743615146504.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/DRONE-1-e1743615146504.jpg\" alt=\"DCIM102MEDIADJI_0979.JPG\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/dcim102mediadji_0979-jpg\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/DRONE-1-e1743615146504.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2791 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-2-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-2-scaled.jpg\" alt=\"ULIVO-2\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-2\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-2-scaled.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2792 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-3-e1743615122658.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-3-e1743615122658.jpg\" alt=\"ULIVO-3\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-3\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-3-e1743615122658.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2793 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-4-e1743615108784.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-4-e1743615108784.jpg\" alt=\"ULIVO-4\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-4\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-4-e1743615108784.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2794 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-5-e1743615089944.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-5-e1743615089944.jpg\" alt=\"ULIVO-5\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-5\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-5-e1743615089944.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2795 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-6-e1743615075967.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-6-e1743615075967.jpg\" alt=\"ULIVO-6\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-6\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-6-e1743615075967.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2796 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-7-e1743615058433.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-7-e1743615058433.jpg\" alt=\"ULIVO-7\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-7\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-7-e1743615058433.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2819 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-39-scaled-e1743597281149.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-39-scaled-e1743597281149.jpg\" alt=\"ULIVO-39\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-39\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-39-scaled-e1743597281149.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2821 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-41-scaled-e1743597263689.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-41-scaled-e1743597263689.jpg\" alt=\"ULIVO-41\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-41\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-41-scaled-e1743597263689.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2797 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-10-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-10-scaled.jpg\" alt=\"ULIVO-10\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-10\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-10-scaled.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2798 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-12-scaled-e1743615038400.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-12-scaled-e1743615038400.jpg\" alt=\"ULIVO-12\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-12\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-12-scaled-e1743615038400.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2799 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-13-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-13-scaled.jpg\" alt=\"ULIVO-13\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-13\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-13-scaled.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2800 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-14-e1743615022591.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-14-e1743615022591.jpg\" alt=\"ULIVO-14\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-14\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-14-e1743615022591.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2801 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-15-e1743615006526.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-15-e1743615006526.jpg\" alt=\"ULIVO-15\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-15\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-15-e1743615006526.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2802 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-17-e1743614996479.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-17-e1743614996479.jpg\" alt=\"ULIVO-17\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-17\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-17-e1743614996479.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2803 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-20-e1743614983233.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-20-e1743614983233.jpg\" alt=\"ULIVO-20\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-20\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-20-e1743614983233.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2804 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-21-e1743614970355.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-21-e1743614970355.jpg\" alt=\"ULIVO-21\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-21\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-21-e1743614970355.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2805 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-22-scaled-e1743614956598.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-22-scaled-e1743614956598.jpg\" alt=\"ULIVO-22\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-22\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-22-scaled-e1743614956598.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2806 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-23-e1743614944762.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-23-e1743614944762.jpg\" alt=\"ULIVO-23\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-23\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-23-e1743614944762.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2807 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-24-scaled-e1743614926826.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-24-scaled-e1743614926826.jpg\" alt=\"ULIVO-24\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-24\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-24-scaled-e1743614926826.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2808 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-25-e1743614916388.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-25-e1743614916388.jpg\" alt=\"ULIVO-25\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-25\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-25-e1743614916388.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2809 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-26-e1743597395143.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-26-e1743597395143.jpg\" alt=\"ULIVO-26\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-26\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-26-e1743597395143.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2810 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-28-e1743597383855.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-28-e1743597383855.jpg\" alt=\"ULIVO-28\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-28\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-28-e1743597383855.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2811 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-29-e1743597372741.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-29-e1743597372741.jpg\" alt=\"ULIVO-29\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-29\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-29-e1743597372741.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2812 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-30-e1743597358738.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-30-e1743597358738.jpg\" alt=\"ULIVO-30\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-30\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-30-e1743597358738.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2813 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-32-e1743597346618.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-32-e1743597346618.jpg\" alt=\"ULIVO-32\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-32\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-32-e1743597346618.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-3375 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2026\/04\/PHOTO-2026-04-08-10-16-54_9.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2026\/04\/PHOTO-2026-04-08-10-16-54_9.jpg\" alt=\"Bagno\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/photo-2026-04-08-10-16-54_9\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2026\/04\/PHOTO-2026-04-08-10-16-54_9.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-3374 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2026\/04\/PHOTO-2026-04-08-10-16-54_6.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2026\/04\/PHOTO-2026-04-08-10-16-54_6.jpg\" alt=\"Bagno_1\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/photo-2026-04-08-10-16-54_6\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2026\/04\/PHOTO-2026-04-08-10-16-54_6.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-3373 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2026\/04\/PHOTO-2026-04-08-10-16-54_4.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2026\/04\/PHOTO-2026-04-08-10-16-54_4.jpg\" alt=\"Bagno_2\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/photo-2026-04-08-10-16-54_4\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2026\/04\/PHOTO-2026-04-08-10-16-54_4.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2814 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-33-e1743597335960.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-33-e1743597335960.jpg\" alt=\"ULIVO-33\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-33\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-33-e1743597335960.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2815 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-35-scaled-e1743597321674.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-35-scaled-e1743597321674.jpg\" alt=\"ULIVO-35\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-35\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-35-scaled-e1743597321674.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2816 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-36-e1743597313810.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-36-e1743597313810.jpg\" alt=\"ULIVO-36\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-36\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-36-e1743597313810.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2817 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-37-e1743597302820.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-37-e1743597302820.jpg\" alt=\"ULIVO-37\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-37\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-37-e1743597302820.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-2818 attachment type-attachment status-inherit hentry\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-small \"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-38-e1743597292974.jpg\"><img decoding=\"async\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-38-e1743597292974.jpg\" alt=\"ULIVO-38\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-out wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/holidaysicily.net\/en\/ulivo-38\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-lightbox elementor-repeater-item-645b48a wpr-grid-item-display-block wpr-grid-item-align-center wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><span data-src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/06\/ULIVO-38-e1743597292974.jpg\"><i class=\"fas fa-search\"><\/i><\/span><div class=\"wpr-grid-lightbox-overlay\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c65db0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1c65db0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ad67df elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3ad67df\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INFO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b4e715 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8b4e715\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ulteriori informazioni<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-488327f elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"488327f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Check-in dalle ore 15:00, oppure concordando con il proprietario se l&#8217;appartamento \u00e8 libero prima.<\/p><p>Check-out ore 10:00, oppure concordando con il proprietario se l&#8217;appartamento \u00e8 libero.<\/p><p>Disponiamo di noleggio auto, moto e gommone, anche con skipper.<\/p><p>E&#8217; necessaria l&#8217;auto per poter visitare i tantissimi luoghi turistici della Sicilia occidentale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83d2a11 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"83d2a11\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33e266b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"33e266b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73ebad8 e-transform elementor-widget elementor-widget-image\" data-id=\"73ebad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.98,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/0.98\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"227\" src=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png\" class=\"attachment-large size-large wp-image-287\" alt=\"\" srcset=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png 1024w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-300x85.png 300w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-768x218.png 768w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1536x436.png 1536w, https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f3f7db e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"9f3f7db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d67d307 wpr-main-menu-align-center wpr-pointer-line-fx wpr-pointer-fx-slide wpr-main-menu-align--tabletcenter wpr-mobile-menu-custom-width elementor-hidden-mobile wpr-main-menu-align--laptopleft wpr-main-menu-align--mobileleft wpr-pointer-underline wpr-sub-icon-caret-down wpr-sub-menu-fx-fade wpr-nav-menu-bp-mobile wpr-mobile-menu-drdown-align-center wpr-mobile-menu-item-align-center wpr-mobile-toggle-v1 wpr-sub-divider-yes elementor-widget elementor-widget-wpr-nav-menu\" data-id=\"d67d307\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;menu_layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"wpr-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"wpr-nav-menu-container wpr-nav-menu-horizontal\" data-trigger=\"hover\" data-consider-header=\"\" data-scroll-speed=\"500\"><ul id=\"menu-1-d67d307\" class=\"wpr-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-87\"><a href=\"https:\/\/holidaysicily.net\/en\/\" class=\"wpr-menu-item wpr-pointer-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-97\"><a href=\"https:\/\/holidaysicily.net\/en\/villa\/\" class=\"wpr-menu-item wpr-pointer-item\">Villa<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-98\"><a href=\"https:\/\/holidaysicily.net\/en\/appartamenti\/\" class=\"wpr-menu-item wpr-pointer-item\">Appartamenti<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1462\"><a href=\"https:\/\/holidaysicily.net\/en\/noleggio-auto\/\" class=\"wpr-menu-item wpr-pointer-item\">Noleggio auto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-96\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/holidaysicily.net\/en\/contattaci\/\" class=\"wpr-menu-item wpr-pointer-item\">Contatti<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2403\"><a href=\"https:\/\/holidaysicily.net\/en\/dove-siamo\/\" class=\"wpr-sub-menu-item\">Dove siamo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-101\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/holidaysicily.net\/en\/servizi\/\" class=\"wpr-menu-item wpr-pointer-item\">Servizi<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1463\"><a href=\"https:\/\/holidaysicily.net\/en\/escursioni-in-barca\/\" class=\"wpr-sub-menu-item\">Escursioni in barca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1464\"><a href=\"https:\/\/holidaysicily.net\/en\/segesta-tour-4x4\/\" class=\"wpr-sub-menu-item\">Segesta Tour 4\u00d74<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-1948\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"#\" class=\"wpr-menu-item wpr-pointer-item\">Altro<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-100\"><a href=\"https:\/\/holidaysicily.net\/en\/condizioni\/\" class=\"wpr-sub-menu-item\">Condizioni<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-99\"><a href=\"https:\/\/holidaysicily.net\/en\/nei-dintorni\/\" class=\"wpr-sub-menu-item\">Nei Dintorni<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav><nav class=\"wpr-mobile-nav-menu-container\"><div class=\"wpr-mobile-toggle-wrap\"><div class=\"wpr-mobile-toggle\"><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><\/div><\/div><ul id=\"mobile-menu-2-d67d307\" class=\"wpr-mobile-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-87\"><a href=\"https:\/\/holidaysicily.net\/en\/\" class=\"wpr-mobile-menu-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-97\"><a href=\"https:\/\/holidaysicily.net\/en\/villa\/\" class=\"wpr-mobile-menu-item\">Villa<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-98\"><a href=\"https:\/\/holidaysicily.net\/en\/appartamenti\/\" class=\"wpr-mobile-menu-item\">Appartamenti<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1462\"><a href=\"https:\/\/holidaysicily.net\/en\/noleggio-auto\/\" class=\"wpr-mobile-menu-item\">Noleggio auto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-96\"><a href=\"https:\/\/holidaysicily.net\/en\/contattaci\/\" class=\"wpr-mobile-menu-item\">Contatti<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2403\"><a href=\"https:\/\/holidaysicily.net\/en\/dove-siamo\/\" class=\"wpr-mobile-sub-menu-item\">Dove siamo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-101\"><a href=\"https:\/\/holidaysicily.net\/en\/servizi\/\" class=\"wpr-mobile-menu-item\">Servizi<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1463\"><a href=\"https:\/\/holidaysicily.net\/en\/escursioni-in-barca\/\" class=\"wpr-mobile-sub-menu-item\">Escursioni in barca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1464\"><a href=\"https:\/\/holidaysicily.net\/en\/segesta-tour-4x4\/\" class=\"wpr-mobile-sub-menu-item\">Segesta Tour 4\u00d74<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-1948\"><a href=\"#\" class=\"wpr-mobile-menu-item\">Altro<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-100\"><a href=\"https:\/\/holidaysicily.net\/en\/condizioni\/\" class=\"wpr-mobile-sub-menu-item\">Condizioni<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-99\"><a href=\"https:\/\/holidaysicily.net\/en\/nei-dintorni\/\" class=\"wpr-mobile-sub-menu-item\">Nei Dintorni<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58b1182 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"58b1182\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4d5a2f elementor-widget elementor-widget-text-editor\" data-id=\"f4d5a2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Copyright \u00a9 2024 Tutti i Diritti Riservati | Holiday Sicily<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>+39 333 9360695 +39 366 2522334 Via delle Ostriche 47, Alcamo, Italy holidaysicily65@gmail.com Facebook Instagram Home Villa Appartamenti Noleggio auto Home Villa Appartamenti Noleggio auto Servizi Noleggio auto Escursioni in barca Segesta Tour 4\u00d74 Altro Nei Dintorni Condizioni Contatti Dove siamo Servizi Noleggio auto Escursioni in barca Segesta Tour 4\u00d74 Altro Nei Dintorni Condizioni Contatti Dove siamo Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Appartamento Ulivo Appartamento Scopri l&#8217;appartamento Ulivo Appartamento accogliente con vista panoramica sul mare, l\u2019appartamento Ulivo si distingue per interni raffinati, ampio balcone e tonalit\u00e0 naturali che creano un\u2019atmosfera serena e rilassante. Descrizione La casa \u00e8 ubicata in un tranquillo quartiere, su una stradina di 200 metri dal mare, in localit\u00e0 Alcamo Marina, distante 4 km circa dal capoluogo comunale di Alcamo, Balestrate e Castellammare del Golfo. E&#8217; situata al centro del Golfo di Castellammare, caratterizzata da una grande spiaggia di sabbia dorata (lunga circa 7 km), considerata tra le pi\u00f9 belle d&#8217;Italia, sia per estensione che per la qualit\u00e0 della sabbia. 2 Matrimoniali 1 Divano Letto 1 Bagni 6 Persone Interno 2 camere da letto matrimoniali 1 divano letto una piazza 1\/2 nel soggiorno\/cucina 1 bagno completo di box doccia TV Satellitare, frigo, congelatore, lavatrice, condizionatore, cucina completa di forno a microonde e utensili vari Esterno Grande balcone con veranda vista mare, con arredamento da giardino 1 posto auto, parcheggio interno alla struttura Servizi Servizi inclusi WI-FI Servizio wifi gratuito Lenzuola e asciugamani Inclusi nel prezzo Energia elettrica, gas e acqua Tutto incluso Parcheggio 1 posto auto Servizi non inclusi *La piscina \u00e8 ad uso esclusivo\u00a0della Villa Oleandro. Cambio lenzuola, cambio asciugamani e possibilit\u00e0 di pulizia extra dell&#8217;appartamento. Contattare la struttura per aggiungere i servizi. Foto dell&#8217;appartamento Scopri l&#8217;interno e l&#8217;esterno dell&#8217;appartamento Ulivo Scopri INFO Ulteriori informazioni Check-in dalle ore 15:00, oppure concordando con il proprietario se l&#8217;appartamento \u00e8 libero prima. Check-out ore 10:00, oppure concordando con il proprietario se l&#8217;appartamento \u00e8 libero. Disponiamo di noleggio auto, moto e gommone, anche con skipper. E&#8217; necessaria l&#8217;auto per poter visitare i tantissimi luoghi turistici della Sicilia occidentale. Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Copyright \u00a9 2024 Tutti i Diritti Riservati | Holiday Sicily<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"blank-slate-template.php","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-976","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ulivo - Holiday Sicily<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/holidaysicily.net\/en\/ulivo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ulivo - Holiday Sicily\" \/>\n<meta property=\"og:description\" content=\"+39 333 9360695 +39 366 2522334 Via delle Ostriche 47, Alcamo, Italy holidaysicily65@gmail.com Facebook Instagram Home Villa Appartamenti Noleggio auto Home Villa Appartamenti Noleggio auto Servizi Noleggio auto Escursioni in barca Segesta Tour 4\u00d74 Altro Nei Dintorni Condizioni Contatti Dove siamo Servizi Noleggio auto Escursioni in barca Segesta Tour 4\u00d74 Altro Nei Dintorni Condizioni Contatti Dove siamo Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Appartamento Ulivo Appartamento Scopri l&#8217;appartamento Ulivo Appartamento accogliente con vista panoramica sul mare, l\u2019appartamento Ulivo si distingue per interni raffinati, ampio balcone e tonalit\u00e0 naturali che creano un\u2019atmosfera serena e rilassante. Descrizione La casa \u00e8 ubicata in un tranquillo quartiere, su una stradina di 200 metri dal mare, in localit\u00e0 Alcamo Marina, distante 4 km circa dal capoluogo comunale di Alcamo, Balestrate e Castellammare del Golfo. E&#8217; situata al centro del Golfo di Castellammare, caratterizzata da una grande spiaggia di sabbia dorata (lunga circa 7 km), considerata tra le pi\u00f9 belle d&#8217;Italia, sia per estensione che per la qualit\u00e0 della sabbia. 2 Matrimoniali 1 Divano Letto 1 Bagni 6 Persone Interno 2 camere da letto matrimoniali 1 divano letto una piazza 1\/2 nel soggiorno\/cucina 1 bagno completo di box doccia TV Satellitare, frigo, congelatore, lavatrice, condizionatore, cucina completa di forno a microonde e utensili vari Esterno Grande balcone con veranda vista mare, con arredamento da giardino 1 posto auto, parcheggio interno alla struttura Servizi Servizi inclusi WI-FI Servizio wifi gratuito Lenzuola e asciugamani Inclusi nel prezzo Energia elettrica, gas e acqua Tutto incluso Parcheggio 1 posto auto Servizi non inclusi *La piscina \u00e8 ad uso esclusivo\u00a0della Villa Oleandro. Cambio lenzuola, cambio asciugamani e possibilit\u00e0 di pulizia extra dell&#8217;appartamento. Contattare la struttura per aggiungere i servizi. Foto dell&#8217;appartamento Scopri l&#8217;interno e l&#8217;esterno dell&#8217;appartamento Ulivo Scopri INFO Ulteriori informazioni Check-in dalle ore 15:00, oppure concordando con il proprietario se l&#8217;appartamento \u00e8 libero prima. Check-out ore 10:00, oppure concordando con il proprietario se l&#8217;appartamento \u00e8 libero. Disponiamo di noleggio auto, moto e gommone, anche con skipper. E&#8217; necessaria l&#8217;auto per poter visitare i tantissimi luoghi turistici della Sicilia occidentale. Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Copyright \u00a9 2024 Tutti i Diritti Riservati | Holiday Sicily\" \/>\n<meta property=\"og:url\" content=\"https:\/\/holidaysicily.net\/en\/ulivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Holiday Sicily\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolidaySicilyCasaVacanze\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T08:49:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/ulivo\\\/\",\"url\":\"https:\\\/\\\/holidaysicily.net\\\/ulivo\\\/\",\"name\":\"Ulivo - Holiday Sicily\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/ulivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/ulivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/holidaysicily.net\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_Bianco_1-1024x291.png\",\"datePublished\":\"2024-01-21T16:15:14+00:00\",\"dateModified\":\"2026-04-08T08:49:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/ulivo\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/holidaysicily.net\\\/ulivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/ulivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/holidaysicily.net\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_Bianco_1-1024x291.png\",\"contentUrl\":\"https:\\\/\\\/holidaysicily.net\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_Bianco_1-1024x291.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/ulivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holidaysicily.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ulivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/#website\",\"url\":\"https:\\\/\\\/holidaysicily.net\\\/\",\"name\":\"Holiday Sicily\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/holidaysicily.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/#organization\",\"name\":\"Holiday Sicily\",\"url\":\"https:\\\/\\\/holidaysicily.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/holidaysicily.net\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_Bianco_1.png\",\"contentUrl\":\"https:\\\/\\\/holidaysicily.net\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_Bianco_1.png\",\"width\":2000,\"height\":568,\"caption\":\"Holiday Sicily\"},\"image\":{\"@id\":\"https:\\\/\\\/holidaysicily.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HolidaySicilyCasaVacanze\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ulivo - Holiday Sicily","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/holidaysicily.net\/en\/ulivo\/","og_locale":"en_GB","og_type":"article","og_title":"Ulivo - Holiday Sicily","og_description":"+39 333 9360695 +39 366 2522334 Via delle Ostriche 47, Alcamo, Italy holidaysicily65@gmail.com Facebook Instagram Home Villa Appartamenti Noleggio auto Home Villa Appartamenti Noleggio auto Servizi Noleggio auto Escursioni in barca Segesta Tour 4\u00d74 Altro Nei Dintorni Condizioni Contatti Dove siamo Servizi Noleggio auto Escursioni in barca Segesta Tour 4\u00d74 Altro Nei Dintorni Condizioni Contatti Dove siamo Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Appartamento Ulivo Appartamento Scopri l&#8217;appartamento Ulivo Appartamento accogliente con vista panoramica sul mare, l\u2019appartamento Ulivo si distingue per interni raffinati, ampio balcone e tonalit\u00e0 naturali che creano un\u2019atmosfera serena e rilassante. Descrizione La casa \u00e8 ubicata in un tranquillo quartiere, su una stradina di 200 metri dal mare, in localit\u00e0 Alcamo Marina, distante 4 km circa dal capoluogo comunale di Alcamo, Balestrate e Castellammare del Golfo. E&#8217; situata al centro del Golfo di Castellammare, caratterizzata da una grande spiaggia di sabbia dorata (lunga circa 7 km), considerata tra le pi\u00f9 belle d&#8217;Italia, sia per estensione che per la qualit\u00e0 della sabbia. 2 Matrimoniali 1 Divano Letto 1 Bagni 6 Persone Interno 2 camere da letto matrimoniali 1 divano letto una piazza 1\/2 nel soggiorno\/cucina 1 bagno completo di box doccia TV Satellitare, frigo, congelatore, lavatrice, condizionatore, cucina completa di forno a microonde e utensili vari Esterno Grande balcone con veranda vista mare, con arredamento da giardino 1 posto auto, parcheggio interno alla struttura Servizi Servizi inclusi WI-FI Servizio wifi gratuito Lenzuola e asciugamani Inclusi nel prezzo Energia elettrica, gas e acqua Tutto incluso Parcheggio 1 posto auto Servizi non inclusi *La piscina \u00e8 ad uso esclusivo\u00a0della Villa Oleandro. Cambio lenzuola, cambio asciugamani e possibilit\u00e0 di pulizia extra dell&#8217;appartamento. Contattare la struttura per aggiungere i servizi. Foto dell&#8217;appartamento Scopri l&#8217;interno e l&#8217;esterno dell&#8217;appartamento Ulivo Scopri INFO Ulteriori informazioni Check-in dalle ore 15:00, oppure concordando con il proprietario se l&#8217;appartamento \u00e8 libero prima. Check-out ore 10:00, oppure concordando con il proprietario se l&#8217;appartamento \u00e8 libero. Disponiamo di noleggio auto, moto e gommone, anche con skipper. E&#8217; necessaria l&#8217;auto per poter visitare i tantissimi luoghi turistici della Sicilia occidentale. Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Home Villa Appartamenti Noleggio auto Contatti Dove siamo Servizi Escursioni in barca Segesta Tour 4\u00d74 Altro Condizioni Nei Dintorni Copyright \u00a9 2024 Tutti i Diritti Riservati | Holiday Sicily","og_url":"https:\/\/holidaysicily.net\/en\/ulivo\/","og_site_name":"Holiday Sicily","article_publisher":"https:\/\/www.facebook.com\/HolidaySicilyCasaVacanze\/","article_modified_time":"2026-04-08T08:49:50+00:00","og_image":[{"url":"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/holidaysicily.net\/ulivo\/","url":"https:\/\/holidaysicily.net\/ulivo\/","name":"Ulivo - Holiday Sicily","isPartOf":{"@id":"https:\/\/holidaysicily.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/holidaysicily.net\/ulivo\/#primaryimage"},"image":{"@id":"https:\/\/holidaysicily.net\/ulivo\/#primaryimage"},"thumbnailUrl":"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png","datePublished":"2024-01-21T16:15:14+00:00","dateModified":"2026-04-08T08:49:50+00:00","breadcrumb":{"@id":"https:\/\/holidaysicily.net\/ulivo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/holidaysicily.net\/ulivo\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/holidaysicily.net\/ulivo\/#primaryimage","url":"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png","contentUrl":"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1-1024x291.png"},{"@type":"BreadcrumbList","@id":"https:\/\/holidaysicily.net\/ulivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/holidaysicily.net\/"},{"@type":"ListItem","position":2,"name":"Ulivo"}]},{"@type":"WebSite","@id":"https:\/\/holidaysicily.net\/#website","url":"https:\/\/holidaysicily.net\/","name":"Holiday Sicily","description":"","publisher":{"@id":"https:\/\/holidaysicily.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/holidaysicily.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/holidaysicily.net\/#organization","name":"Holiday Sicily","url":"https:\/\/holidaysicily.net\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/holidaysicily.net\/#\/schema\/logo\/image\/","url":"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1.png","contentUrl":"https:\/\/holidaysicily.net\/wp-content\/uploads\/2024\/01\/Logo_Bianco_1.png","width":2000,"height":568,"caption":"Holiday Sicily"},"image":{"@id":"https:\/\/holidaysicily.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HolidaySicilyCasaVacanze\/"]}]}},"_links":{"self":[{"href":"https:\/\/holidaysicily.net\/en\/wp-json\/wp\/v2\/pages\/976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holidaysicily.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/holidaysicily.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/holidaysicily.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/holidaysicily.net\/en\/wp-json\/wp\/v2\/comments?post=976"}],"version-history":[{"count":100,"href":"https:\/\/holidaysicily.net\/en\/wp-json\/wp\/v2\/pages\/976\/revisions"}],"predecessor-version":[{"id":3378,"href":"https:\/\/holidaysicily.net\/en\/wp-json\/wp\/v2\/pages\/976\/revisions\/3378"}],"wp:attachment":[{"href":"https:\/\/holidaysicily.net\/en\/wp-json\/wp\/v2\/media?parent=976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}